{"id":98740,"date":"2019-11-19T14:34:35","date_gmt":"2019-11-19T14:34:35","guid":{"rendered":"https:\/\/evc.extramilecommunications.dev\/?p=98740"},"modified":"2024-12-19T10:47:04","modified_gmt":"2024-12-19T10:47:04","slug":"chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics","status":"publish","type":"post","link":"https:\/\/www.evcargo.com\/de\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/","title":{"rendered":"Chinas Belt and Road Initiative \u2013 Wie die neue Seidenstra\u00dfe die globale Logistik verbessern wird"},"content":{"rendered":"<section  class=\"wysiwyg\">\n\n\t<div class=\"container-fluid\">\n\n\t<p><strong>Allport Cargo Services hat die Einf\u00fchrung von Chinas Belt and Road Initiative (BRI) aufmerksam verfolgt. Das ehrgeizige Programm zielt darauf ab, Asien mit Afrika und Europa \u00fcber Stra\u00dfen-, Bahn- und Seeverkehrsnetze entlang von sechs Korridoren zu verbinden. Mit einer st\u00e4ndig wachsenden Reichweite deckt es derzeit 70 L\u00e4nder ab, 651 TP1 T der Weltbev\u00f6lkerung und umfasst ein Drittel des weltweiten BIP. Was sind die Urspr\u00fcnge des BRI, was sind seine Herausforderungen und welche Implikationen ergeben sich f\u00fcr den globalen Handel und die Logistik?<\/strong><\/p>\n<p>Die BRI ist Chinas wichtigste Strategie des globalen Engagements und zielt darauf ab, die regionale Integration zu verbessern, den Handel zu steigern und das Wirtschaftswachstum anzukurbeln. Handel und Logistik auf diesen Routen sind derzeit aufgrund mangelnder Konnektivit\u00e4t und schlechter Infrastruktur eine Herausforderung; ein Problem, das sich auf den Betrieb der Lieferkette auswirken kann. Die f\u00fcnf Hauptpriorit\u00e4ten des BRI sind politische Koordinierung, Infrastrukturanbindung, ungehinderter Handel, finanzielle Integration und Verbindung von Menschen. Die geplanten Bauvorhaben sind von unvergleichlichem Ausma\u00df und L\u00e4nder entlang der Strecke haben ihre Unterst\u00fctzung zugesagt.<\/p>\n<p><strong>Eine neue \u201eSeidenstra\u00dfe\u201c<\/strong><\/p>\n<p>Die 2013 angek\u00fcndigte Belt-and-Road-Initiative wurde von Chinas Pr\u00e4sident Xi Jinping benannt und steht im Mittelpunkt seines \u201echinesischen Traums\u201c und seiner charakteristischen Au\u00dfenpolitik. Der Name ist vom Konzept der Seidenstra\u00dfe inspiriert \u2013 einem Netzwerk von Handelsrouten, das 130 v. Chr. Als die Han-Dynastie den Handel mit dem Westen er\u00f6ffnete. Die Seidenstra\u00dfenrouten verbanden China mit dem Mittelmeer und Eurasien und existierten bis 1453 n. Chr., als das Osmanische Reich den Handel mit China boykottierte und schloss. Durch diese Wege wurden die Papierherstellung, der Druck, das Schie\u00dfpulver, der Kompass und das Seidenspinnen in den Westen eingef\u00fchrt. Diese neue \u201eSeidenstra\u00dfe\u201c von Handelsrouten ist sowohl in geografischer als auch in wirtschaftlicher Hinsicht breiter.<\/p>\n<p><strong>Themen und Debatte<\/strong><\/p>\n<p>Die Ungeheuerlichkeit dieses Unterfangens ist nicht zu untersch\u00e4tzen. Als teuerstes Infrastrukturprojekt der Geschichte wird es voraussichtlich beinhalten\u00a0<a href=\"https:\/\/www.morganstanley.com\/ideas\/china-belt-and-road\">US $1 Billionen<\/a>\u00a0in Investitionen f\u00fcr den Infrastrukturausbau von H\u00e4fen, Stra\u00dfen, Eisenbahnen und Flugh\u00e4fen sowie Kraftwerken und Telekommunikationsnetzen.<\/p>\n<p>China hat einen \u00dcberschuss an Kapazit\u00e4ten und Ressourcen. Es produziert auch mehr Stahl, als es ben\u00f6tigt. Die BRI m\u00f6chte diese Kapazit\u00e4ten auf neue M\u00e4rkte verlagern, den Lebensstandard verbessern und dabei abgelegene l\u00e4ndliche Gebiete verbinden. Durch die Verbesserung der Infrastruktur hofft China, die Industrialisierung in \u00e4rmeren Gebieten anzukurbeln.<\/p>\n<p>Indonesien erh\u00e4lt Investitionen in G\u00fcrtel und Stra\u00dfen. In der Region, in der Teeplantagen die Landschaft f\u00fcllen und die Menschen noch mit Bambusstangen fischen, sind die S-Bahnen alt und langsam, und die Stra\u00dfen machen die Logistik teuer. Derzeit ist die Stra\u00dfe von Jakarta nach Bandung eine 90-Meilen-Fahrt, die f\u00fcnf Stunden dauert. Um dem zu begegnen, wird in einem $6bn-Projekt ein Tunnel f\u00fcr einen Hochgeschwindigkeitszug gebaut, der der schnellste Zug in S\u00fcdasien sein wird; in der Lage, mit 215 Meilen pro Stunde zu reisen. Die neue Bahn verk\u00fcrzt die gleiche Fahrt auf 45 Minuten. China arbeitet mit indonesischen Unternehmen zusammen, um zusammenzuarbeiten und Menschen aus der Armut zu befreien. Chinesische Fachkr\u00e4fte bilden ungelernte Indonesier aus und schaffen neue Industrien, Arbeitspl\u00e4tze und Produktionen.<\/p>\n<p>Die Strategie \u201eOne Belt, One Road\u201c bleibt jedoch nicht ohne Kritik. Es gibt Berichte, dass China $340 Mrd. an Bauauftr\u00e4gen gesichert hat und lokale Auftragnehmer in Partnerl\u00e4ndern verlieren. Es gibt auch Bedenken, dass es gef\u00e4hrdete L\u00e4nder dr\u00e4ngen k\u00f6nnte \u2013 wie z\u00a0<a href=\"https:\/\/www.cgdev.org\/blog\/will-chinas-belt-and-road-initiative-push-vulnerable-countries-debt-crisis?gclid=Cj0KCQiA-4nuBRCnARIsAHwyuPpUpQZ6LNgItCdxQ5mHZPmqOllx-nKKCB-h4UgUdFbzeuHyVyHmmGYaAifsEALw_wcB\">Mongolei, Laos und Pakistan<\/a>\u00a0\u2013 in eine Schuldenkrise.<\/p>\n<p>&nbsp;<\/p>\n<p>In Malaysia wurde der Premierminister Mahathir Mohammed im Alter von 92 Jahren wiedergew\u00e4hlt. Damals nannte er G\u00fcrtel- und Stra\u00dfenprojekte r\u00e4uberisch, alle Teile, Materialien und Ressourcen k\u00e4men aus China und Zahlungen w\u00fcrden in China geleistet. Mohammed verhandelte mit China neu, um eine neue Bahnverbindung zu schaffen, nachdem der Baupreis um 30% gesenkt worden war, mit mehr Besch\u00e4ftigung f\u00fcr malaysische Arbeiter.<\/p>\n<p>Obwohl in umweltfreundlichere Verkehrsnetze wie die Schiene (den \u201eG\u00fcrtel\u201c) investiert wird, warnt der WWF davor, dass sich geplante Korridore mit 265 bedrohten Arten \u00fcberschneiden, was vor allem in \u00e4rmeren L\u00e4ndern mit schw\u00e4cheren Umweltvorschriften enorme Umweltfolgen haben wird.<\/p>\n<p><strong>Blue Dot Network \u2013 ein Rivale von BRI<\/strong><\/p>\n<p>Nachdem die USA China beschuldigt hatten, \u201ePartner in einem Meer von Schulden zu ertrinken\u201c, unterst\u00fctzten die USA k\u00fcrzlich einen Infrastrukturplan, um mit der BRI zu konkurrieren. Das &#039;Blue Dot Network&#039; will aus dem Unbehagen in Asien \u00fcber die Risiken der BRI Kapital schlagen und hat eine Zertifizierung f\u00fcr internationale Standards f\u00fcr gro\u00dfe Infrastrukturprojekte vorgestellt. Es hat $17 Milliarden US-Dollar f\u00fcr Projekte im Rahmen des Programms zugesagt.<\/p>\n<p>Die Ank\u00fcndigung kam in derselben Woche, dass es\u00a0<a href=\"https:\/\/www.cgdev.org\/blog\/will-chinas-belt-and-road-initiative-push-vulnerable-countries-debt-crisis?gclid=Cj0KCQiA-4nuBRCnARIsAHwyuPpUpQZ6LNgItCdxQ5mHZPmqOllx-nKKCB-h4UgUdFbzeuHyVyHmmGYaAifsEALw_wcB\">positive zeichen<\/a>\u00a0Der Handelskrieg zwischen den USA und China, der das Wirtschaftswachstum gebremst hat, neigt sich dem Ende zu, da sich die beiden gr\u00f6\u00dften Volkswirtschaften der Welt auf eine schrittweise Reduzierung der Z\u00f6lle einigen. Mit einem Handelsdefizit von \u00fcber $300 Milliarden wollen die USA, dass China mehr von seinen Waren kauft, und der Handelskrieg f\u00fchrte zu Z\u00f6llen auf Waren in Milliardenh\u00f6he, auf die China mit weiteren Zollerh\u00f6hungen revanchierte.<\/p>\n<p><strong>Auswirkungen auf Logistik und Lieferkette<\/strong><\/p>\n<p>Es besteht kein Zweifel, dass dies gro\u00dfe Auswirkungen auf den Welthandel hat. Eine starke Logistik bedeutet, dass Produkte mehr Verbraucher mit erh\u00f6hter Sicherheit und Geschwindigkeit erreichen k\u00f6nnen und mit zuverl\u00e4ssigeren Transport- und Infrastruktursystemen mehr Unternehmen in Entwicklungsl\u00e4ndern investieren werden. Die BRI wird die globale Konnektivit\u00e4t durch den Export von Infrastrukturentwicklungskapazit\u00e4ten st\u00e4rken.<\/p>\n<p>ACS verfolgt die Fortschritte aufmerksam und sucht nach M\u00f6glichkeiten, die wachsende Infrastruktur zu nutzen und zunehmend flexible und skalierbare Routen von und zu den M\u00e4rkten in der gesamten Region zu schaffen. Die L\u00e4nder der ASEAN, Malaysia, Thailand und Indonesien haben gemeinsame Belt-and-Road-Abkommen mit China, haupts\u00e4chlich im Bereich des Eisenbahnbaus. Dies wird S\u00fcdostasien und den indischen Subkontinent verbinden, die neben China wichtige Beschaffungsregionen f\u00fcr den Westen sind. S\u00fcdostasien ist wichtig f\u00fcr die Weiterentwicklung der Initiative, die L\u00fccken bei den Infrastrukturinvestitionen schlie\u00dft, die die Entwicklung behindert haben.\u00a0<a href=\"https:\/\/blogs.worldbank.org\/trade\/look-logistics-within-belt-and-road-economies\">Ein aktueller Bericht<\/a>\u00a0fanden L\u00fccken im Handel und in der verkehrsbezogenen Infrastruktur in den BRI-Volkswirtschaften. Die Verbesserung der Transportnetze wird China helfen, das intern \u00fcber eine gute Logistikleistung verf\u00fcgt, in den umliegenden L\u00e4ndern jedoch eine schlechte Logistik. Verbesserungen bedeuten auch die Schaffung von Wirtschaftszonen mit mehr Logistikparks und Zolllagern.<\/p>\n\n\t<\/div>\n\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":98741,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[],"postlocation":[],"posttype":[],"postservice":[],"class_list":["post-98740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>China\u2019s Belt and Road Initiative \u2013 How The New Silk Road Will Improve Global Logistics - EV Cargo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.evcargo.com\/de\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"China\u2019s Belt and Road Initiative \u2013 How The New Silk Road Will Improve Global Logistics - EV Cargo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evcargo.com\/de\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/\" \/>\n<meta property=\"og:site_name\" content=\"EV Cargo\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-19T14:34:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-19T10:47:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evcargo.com\/wp-content\/uploads\/2021\/07\/shutterstock_488214391_3600x1680_acf_cropped_1260x840_acf_cropped_1260x840_acf_cropped-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1260\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Extramile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Extramile\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\\\/\"},\"author\":{\"name\":\"Extramile\",\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/#\\\/schema\\\/person\\\/573a241aeca1b761eca1a71200f127c0\"},\"headline\":\"China\u2019s Belt and Road Initiative \u2013 How The New Silk Road Will Improve Global Logistics\",\"datePublished\":\"2019-11-19T14:34:35+00:00\",\"dateModified\":\"2024-12-19T10:47:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\\\/\"},\"wordCount\":15,\"publisher\":{\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evcargo.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/shutterstock_488214391_3600x1680_acf_cropped_1260x840_acf_cropped_1260x840_acf_cropped-1.jpeg\",\"articleSection\":[\"General\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\\\/\",\"url\":\"https:\\\/\\\/www.evcargo.com\\\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\\\/\",\"name\":\"China\u2019s Belt and Road Initiative \u2013 How The New Silk Road Will Improve Global Logistics - EV Cargo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.evcargo.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/shutterstock_488214391_3600x1680_acf_cropped_1260x840_acf_cropped_1260x840_acf_cropped-1.jpeg\",\"datePublished\":\"2019-11-19T14:34:35+00:00\",\"dateModified\":\"2024-12-19T10:47:04+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.evcargo.com\\\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.evcargo.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/shutterstock_488214391_3600x1680_acf_cropped_1260x840_acf_cropped_1260x840_acf_cropped-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.evcargo.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/shutterstock_488214391_3600x1680_acf_cropped_1260x840_acf_cropped_1260x840_acf_cropped-1.jpeg\",\"width\":1260,\"height\":840},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/\",\"name\":\"EV Cargo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/#organization\",\"name\":\"EV Cargo\",\"alternateName\":\"EVC\",\"url\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.evcargo.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ev-cargo-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.evcargo.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ev-cargo-logo.png\",\"width\":364,\"height\":78,\"caption\":\"EV Cargo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.evcargo.com\\\/de\\\/#\\\/schema\\\/person\\\/573a241aeca1b761eca1a71200f127c0\",\"name\":\"Extramile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d168442295cd39d9d3845fd5f8676a34f8965750d91cfb9246fdbef454cb018?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d168442295cd39d9d3845fd5f8676a34f8965750d91cfb9246fdbef454cb018?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d168442295cd39d9d3845fd5f8676a34f8965750d91cfb9246fdbef454cb018?s=96&d=mm&r=g\",\"caption\":\"Extramile\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chinas Belt and Road Initiative \u2013 Wie die Neue Seidenstra\u00dfe die globale Logistik verbessern wird - EV Cargo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.evcargo.com\/de\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/","og_locale":"de_DE","og_type":"article","og_title":"China\u2019s Belt and Road Initiative \u2013 How The New Silk Road Will Improve Global Logistics - EV Cargo","og_url":"https:\/\/www.evcargo.com\/de\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/","og_site_name":"EV Cargo","article_published_time":"2019-11-19T14:34:35+00:00","article_modified_time":"2024-12-19T10:47:04+00:00","og_image":[{"width":1260,"height":840,"url":"https:\/\/www.evcargo.com\/wp-content\/uploads\/2021\/07\/shutterstock_488214391_3600x1680_acf_cropped_1260x840_acf_cropped_1260x840_acf_cropped-1.jpeg","type":"image\/jpeg"}],"author":"Extramile","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Extramile"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.evcargo.com\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/#article","isPartOf":{"@id":"https:\/\/www.evcargo.com\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/"},"author":{"name":"Extramile","@id":"https:\/\/www.evcargo.com\/de\/#\/schema\/person\/573a241aeca1b761eca1a71200f127c0"},"headline":"China\u2019s Belt and Road Initiative \u2013 How The New Silk Road Will Improve Global Logistics","datePublished":"2019-11-19T14:34:35+00:00","dateModified":"2024-12-19T10:47:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.evcargo.com\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/"},"wordCount":15,"publisher":{"@id":"https:\/\/www.evcargo.com\/de\/#organization"},"image":{"@id":"https:\/\/www.evcargo.com\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evcargo.com\/wp-content\/uploads\/2021\/07\/shutterstock_488214391_3600x1680_acf_cropped_1260x840_acf_cropped_1260x840_acf_cropped-1.jpeg","articleSection":["General"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.evcargo.com\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/","url":"https:\/\/www.evcargo.com\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/","name":"Chinas Belt and Road Initiative \u2013 Wie die Neue Seidenstra\u00dfe die globale Logistik verbessern wird - EV Cargo","isPartOf":{"@id":"https:\/\/www.evcargo.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.evcargo.com\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/#primaryimage"},"image":{"@id":"https:\/\/www.evcargo.com\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/#primaryimage"},"thumbnailUrl":"https:\/\/www.evcargo.com\/wp-content\/uploads\/2021\/07\/shutterstock_488214391_3600x1680_acf_cropped_1260x840_acf_cropped_1260x840_acf_cropped-1.jpeg","datePublished":"2019-11-19T14:34:35+00:00","dateModified":"2024-12-19T10:47:04+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evcargo.com\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evcargo.com\/chinas-belt-and-road-initiative-how-the-new-silk-road-will-improve-global-logistics\/#primaryimage","url":"https:\/\/www.evcargo.com\/wp-content\/uploads\/2021\/07\/shutterstock_488214391_3600x1680_acf_cropped_1260x840_acf_cropped_1260x840_acf_cropped-1.jpeg","contentUrl":"https:\/\/www.evcargo.com\/wp-content\/uploads\/2021\/07\/shutterstock_488214391_3600x1680_acf_cropped_1260x840_acf_cropped_1260x840_acf_cropped-1.jpeg","width":1260,"height":840},{"@type":"WebSite","@id":"https:\/\/www.evcargo.com\/de\/#website","url":"https:\/\/www.evcargo.com\/de\/","name":"EV Cargo","description":"","publisher":{"@id":"https:\/\/www.evcargo.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evcargo.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.evcargo.com\/de\/#organization","name":"EV Cargo","alternateName":"EVC","url":"https:\/\/www.evcargo.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.evcargo.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.evcargo.com\/wp-content\/uploads\/2025\/02\/ev-cargo-logo.png","contentUrl":"https:\/\/www.evcargo.com\/wp-content\/uploads\/2025\/02\/ev-cargo-logo.png","width":364,"height":78,"caption":"EV Cargo"},"image":{"@id":"https:\/\/www.evcargo.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.evcargo.com\/de\/#\/schema\/person\/573a241aeca1b761eca1a71200f127c0","name":"Extrameile","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4d168442295cd39d9d3845fd5f8676a34f8965750d91cfb9246fdbef454cb018?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d168442295cd39d9d3845fd5f8676a34f8965750d91cfb9246fdbef454cb018?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d168442295cd39d9d3845fd5f8676a34f8965750d91cfb9246fdbef454cb018?s=96&d=mm&r=g","caption":"Extramile"}}]}},"_links":{"self":[{"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/posts\/98740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/comments?post=98740"}],"version-history":[{"count":1,"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/posts\/98740\/revisions"}],"predecessor-version":[{"id":220790,"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/posts\/98740\/revisions\/220790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/media\/98741"}],"wp:attachment":[{"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/media?parent=98740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/categories?post=98740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/tags?post=98740"},{"taxonomy":"postlocation","embeddable":true,"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/postlocation?post=98740"},{"taxonomy":"posttype","embeddable":true,"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/posttype?post=98740"},{"taxonomy":"postservice","embeddable":true,"href":"https:\/\/www.evcargo.com\/de\/wp-json\/wp\/v2\/postservice?post=98740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}